{"id":4070,"date":"2024-11-02T13:48:11","date_gmt":"2024-11-02T11:48:11","guid":{"rendered":"https:\/\/armionline.net\/listing\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\/"},"modified":"2024-11-02T13:53:14","modified_gmt":"2024-11-02T11:53:14","slug":"revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col","status":"publish","type":"rtcl_listing","link":"https:\/\/armionline.net\/en\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\/","title":{"rendered":"Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col"},"content":{"rendered":"<p>USATO \u2013 REVOLVER \u2013 UBERTI MOD. 1000 1858 NEW IMPR.ARM 8\u2033 cal. 45 COLT\/44 MAG.<\/p>\n<p>Splendido revolver usato in perfette condizioni, come nuovo. Appartenuto a collezionista.<\/p>\n<p>Completo di scatola originale pi\u00f9 secondo tamburo in calibro 44 Magnum avancarica<\/p>","protected":false},"author":20,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-4070","rtcl_listing","type-rtcl_listing","status-publish","hentry","rtcl_category-armi-polvere-nera","rtcl_location-abruzzo","rtcl_location-laquila","listing-item","rtcl-listing-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col | armionline.net<\/title>\n<meta name=\"description\" content=\"USATO \u2013 REVOLVER \u2013 UBERTI MOD. 1000 1858 NEW IMPR.ARM 8\u2033 cal. 45 COLT\/44 MAG. Splendido revolver usato in perfette condizioni, come nuovo. Appartenuto a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armionline.net\/en\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8\u2033-cal-45-col\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col | armionline.net\" \/>\n<meta property=\"og:description\" content=\"USATO \u2013 REVOLVER \u2013 UBERTI MOD. 1000 1858 NEW IMPR.ARM 8\u2033 cal. 45 COLT\/44 MAG. Splendido revolver usato in perfette condizioni, come nuovo. Appartenuto a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armionline.net\/en\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8\u2033-cal-45-col\/\" \/>\n<meta property=\"og:site_name\" content=\"armionline.net\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-02T11:53:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1046\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\\\/\",\"name\":\"Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col | armionline.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\"},\"datePublished\":\"2024-11-02T11:48:11+00:00\",\"dateModified\":\"2024-11-02T11:53:14+00:00\",\"description\":\"USATO \u2013 REVOLVER \u2013 UBERTI MOD. 1000 1858 NEW IMPR.ARM 8\u2033 cal. 45 COLT\\\/44 MAG. Splendido revolver usato in perfette condizioni, come nuovo. Appartenuto a\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armionline.net\\\/annunci\\\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/armionline.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classified Listings\",\"item\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"name\":\"armionline.net\",\"description\":\"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.\",\"publisher\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armionline.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\",\"name\":\"armionline.net\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"contentUrl\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"width\":180,\"height\":71,\"caption\":\"armionline.net\"},\"image\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col | armionline.net","description":"USATO \u2013 REVOLVER \u2013 UBERTI MOD. 1000 1858 NEW IMPR.ARM 8\u2033 cal. 45 COLT\/44 MAG. Splendido revolver usato in perfette condizioni, come nuovo. Appartenuto a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armionline.net\/en\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8\u2033-cal-45-col\/","og_locale":"en_US","og_type":"article","og_title":"Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col | armionline.net","og_description":"USATO \u2013 REVOLVER \u2013 UBERTI MOD. 1000 1858 NEW IMPR.ARM 8\u2033 cal. 45 COLT\/44 MAG. Splendido revolver usato in perfette condizioni, come nuovo. Appartenuto a","og_url":"https:\/\/armionline.net\/en\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8\u2033-cal-45-col\/","og_site_name":"armionline.net","article_modified_time":"2024-11-02T11:53:14+00:00","og_image":[{"width":1046,"height":164,"url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/armionline.net\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\/","url":"https:\/\/armionline.net\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\/","name":"Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col | armionline.net","isPartOf":{"@id":"https:\/\/armionline.net\/#website"},"datePublished":"2024-11-02T11:48:11+00:00","dateModified":"2024-11-02T11:53:14+00:00","description":"USATO \u2013 REVOLVER \u2013 UBERTI MOD. 1000 1858 NEW IMPR.ARM 8\u2033 cal. 45 COLT\/44 MAG. Splendido revolver usato in perfette condizioni, come nuovo. Appartenuto a","breadcrumb":{"@id":"https:\/\/armionline.net\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armionline.net\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/armionline.net\/annunci\/revolver-uberti-1858-new-army-conversion-canna-8%e2%80%b3-cal-45-col\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/armionline.net\/"},{"@type":"ListItem","position":2,"name":"Classified Listings","item":"https:\/\/armionline.net\/annunci\/"},{"@type":"ListItem","position":3,"name":"Revolver UBERTI 1858 New Army Conversion canna 8\u2033 cal 45 Col"}]},{"@type":"WebSite","@id":"https:\/\/armionline.net\/#website","url":"https:\/\/armionline.net\/","name":"armionline.net","description":"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.","publisher":{"@id":"https:\/\/armionline.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armionline.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/armionline.net\/#organization","name":"armionline.net","url":"https:\/\/armionline.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/","url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","contentUrl":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","width":180,"height":71,"caption":"armionline.net"},"image":{"@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing\/4070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing"}],"about":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/types\/rtcl_listing"}],"author":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/comments?post=4070"}],"wp:attachment":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/media?parent=4070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}