{"id":18564,"date":"2026-05-05T17:02:28","date_gmt":"2026-05-05T15:02:28","guid":{"rendered":"https:\/\/armionline.net\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/"},"modified":"2026-05-05T17:08:48","modified_gmt":"2026-05-05T15:08:48","slug":"baionetta-per-ak-47-arsenale-di-izhevsk","status":"publish","type":"rtcl_listing","link":"https:\/\/armionline.net\/en\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/","title":{"rendered":"Baionetta per Ak 47 Arsenale di Izhevsk"},"content":{"rendered":"<p>Baionetta per Ak 47\u00a0\u00a0Arsenale di Izhevsk<\/p>\n<p>&nbsp;<\/p>\n<p>Seguici anche sul nostro sito internet:<\/p>\n<div class=\"responsive-container\"><a href=\"https:\/\/amp-armeria-meazza.myshopify.com\/products\/baionetta-per-ak-47-arsenale-di-izhevsk\">Baionetta per Ak 47 Arsenale di Izhevsk<\/a><\/div>\n<p>&nbsp;<\/p>\n<p>AMP Armeria Meazza di Meazza PierluigiVia Macra 56\/a 12038 Savigliano CN ItalyTel. +39 0172 22432Cell. +39 393 9359640Partita IVA \u2013 IT 03055190049Cod.Fisc.MZZPLG69A31G388<\/p>\n<p>&nbsp;<\/p>\n<p>ACQUISTO E SPEDIZIONE ARMI<\/p>\n<p>Ai sensi del D.lgs 104 del 2018, l\u2019acquisto pu\u00f2 avvenire o per corrispondenza o con le modalit\u00e0 previste dall\u2019art. 45, comma 1, lett. G) del D.Lgs 6 settembre 2005, n. 206.A seguito di ci\u00f2, il cliente interessato ad acquistare un arma potr\u00e0 scegliere se:- provvedere personalmente presso la nostra sede, munito di titolo autorizzativo in corso di validit\u00e0;- farsela spedire al proprio indirizzo, dopo aver ottenuto l\u2019autorizzazione prefettizia;- rivolgersi all\u2019armeria di fiducia a cui appoggiare la spedizione dell\u2019arma acquistata e ritirarla presso di essa.<\/p>","protected":false},"author":86,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-18564","rtcl_listing","type-rtcl_listing","status-publish","hentry","rtcl_category-accessori-armi-lunghe","rtcl_location-cuneo","rtcl_location-piemonte","listing-item","rtcl-listing-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baionetta per Ak 47 Arsenale di Izhevsk | armionline.net<\/title>\n<meta name=\"description\" content=\"Baionetta per Ak 47\u00a0\u00a0Arsenale di Izhevsk &nbsp; Seguici anche sul nostro sito internet:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armionline.net\/en\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baionetta per Ak 47 Arsenale di Izhevsk | armionline.net\" \/>\n<meta property=\"og:description\" content=\"Baionetta per Ak 47\u00a0\u00a0Arsenale di Izhevsk &nbsp; Seguici anche sul nostro sito internet:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armionline.net\/en\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/\" \/>\n<meta property=\"og:site_name\" content=\"armionline.net\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T15:08:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1046\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/baionetta-per-ak-47-arsenale-di-izhevsk\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/baionetta-per-ak-47-arsenale-di-izhevsk\\\/\",\"name\":\"Baionetta per Ak 47 Arsenale di Izhevsk | armionline.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\"},\"datePublished\":\"2026-05-05T15:02:28+00:00\",\"dateModified\":\"2026-05-05T15:08:48+00:00\",\"description\":\"Baionetta per Ak 47\u00a0\u00a0Arsenale di Izhevsk &nbsp; Seguici anche sul nostro sito internet:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/baionetta-per-ak-47-arsenale-di-izhevsk\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armionline.net\\\/annunci\\\/baionetta-per-ak-47-arsenale-di-izhevsk\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/baionetta-per-ak-47-arsenale-di-izhevsk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/armionline.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classified Listings\",\"item\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Baionetta per Ak 47 Arsenale di Izhevsk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"name\":\"armionline.net\",\"description\":\"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.\",\"publisher\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armionline.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\",\"name\":\"armionline.net\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"contentUrl\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"width\":180,\"height\":71,\"caption\":\"armionline.net\"},\"image\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baionetta per Ak 47 Arsenale di Izhevsk | armionline.net","description":"Baionetta per Ak 47\u00a0\u00a0Arsenale di Izhevsk &nbsp; Seguici anche sul nostro sito internet:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armionline.net\/en\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/","og_locale":"en_US","og_type":"article","og_title":"Baionetta per Ak 47 Arsenale di Izhevsk | armionline.net","og_description":"Baionetta per Ak 47\u00a0\u00a0Arsenale di Izhevsk &nbsp; Seguici anche sul nostro sito internet:","og_url":"https:\/\/armionline.net\/en\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/","og_site_name":"armionline.net","article_modified_time":"2026-05-05T15:08:48+00:00","og_image":[{"width":1046,"height":164,"url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/armionline.net\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/","url":"https:\/\/armionline.net\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/","name":"Baionetta per Ak 47 Arsenale di Izhevsk | armionline.net","isPartOf":{"@id":"https:\/\/armionline.net\/#website"},"datePublished":"2026-05-05T15:02:28+00:00","dateModified":"2026-05-05T15:08:48+00:00","description":"Baionetta per Ak 47\u00a0\u00a0Arsenale di Izhevsk &nbsp; Seguici anche sul nostro sito internet:","breadcrumb":{"@id":"https:\/\/armionline.net\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armionline.net\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/armionline.net\/annunci\/baionetta-per-ak-47-arsenale-di-izhevsk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/armionline.net\/"},{"@type":"ListItem","position":2,"name":"Classified Listings","item":"https:\/\/armionline.net\/annunci\/"},{"@type":"ListItem","position":3,"name":"Baionetta per Ak 47 Arsenale di Izhevsk"}]},{"@type":"WebSite","@id":"https:\/\/armionline.net\/#website","url":"https:\/\/armionline.net\/","name":"armionline.net","description":"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.","publisher":{"@id":"https:\/\/armionline.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armionline.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/armionline.net\/#organization","name":"armionline.net","url":"https:\/\/armionline.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/","url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","contentUrl":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","width":180,"height":71,"caption":"armionline.net"},"image":{"@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing\/18564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing"}],"about":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/types\/rtcl_listing"}],"author":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/comments?post=18564"}],"wp:attachment":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/media?parent=18564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}