{"id":18279,"date":"2026-04-15T17:03:11","date_gmt":"2026-04-15T15:03:11","guid":{"rendered":"https:\/\/armionline.net\/annunci\/canne-per-modello-radom-vis-35\/"},"modified":"2026-04-15T17:03:26","modified_gmt":"2026-04-15T15:03:26","slug":"canne-per-modello-radom-vis-35","status":"publish","type":"rtcl_listing","link":"https:\/\/armionline.net\/en\/annunci\/canne-per-modello-radom-vis-35\/","title":{"rendered":"Canne per modello radom vis 35"},"content":{"rendered":"<p>Canne per modello radom vis 35,<\/p>\n<p>calibro 7,65 Para e 9&#215;21<\/p>\n<p>9&#215;21 180\u20ac<\/p>\n<p>7,65 para 150\u20ac<\/p>\n<p>Seguici anche sul nostro sito internet:<\/p>\n<div class=\"responsive-container\"><a href=\"https:\/\/amp-armeria-meazza.myshopify.com\/products\/canne-per-radom-vis-35-7-65-para-e-9x21\">Canne Per radom vis 35 7,65 para e 9&#215;21<\/a><\/div>\n<p>&nbsp;<\/p>\n<p>AMP Armeria Meazza di Meazza Pierluigi Via Macra 56\/a 12038 Savigliano CN Italy Tel. +39 0172 22432 Cell. +39 393 9359640 Partita IVA \u2013 IT 03055190049Cod.Fisc.MZZPLG69A31G388<\/p>\n<p>&nbsp;<\/p>\n<p>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014-SPEDIZIONE ARMI<\/p>\n<p>Ai sensi della vigente normativa (art. 17 della Legge 18\/04\/1975 n\u00b0 110) la compravendita per corrispondenza di armi comuni da sparo \u00e8 vietata, salvo che l\u2019acquirente abbia ottenuto apposito nulla osta del Prefetto della provincia in cui risiede. Anche le armi ad aria compressa di libera vendita rientrano in questa normativa (art. 7 \u2013 Comma 5; Decreto 9 Agosto 2001, n\u00b0 362).Per il ritiro dell\u2019arma acquistata \u00e8 quindi possibile:- provvedere personalmente presso il punto vendita, muniti di titolo autorizzativo in corso di validit\u00e0;-rivolgersi all\u2019armeria di fiducia a cui appoggiare la spedizione dell\u2019arma acquistata e ritirarla presso di essa. Si prega dopo aver eseguito il checkout di contattare l\u2019Armeria Meazza per concordare la modalit\u00e0 di consegna desiderata.<\/p>","protected":false},"author":86,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-18279","rtcl_listing","type-rtcl_listing","status-publish","hentry","rtcl_category-accessori-armi-corte","rtcl_location-cuneo","rtcl_location-piemonte","listing-item","rtcl-listing-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canne per modello radom vis 35 | armionline.net<\/title>\n<meta name=\"description\" content=\"Canne per modello radom vis 35, calibro 7,65 Para e 9x21 9x21 180\u20ac 7,65 para 150\u20ac Seguici anche sul nostro sito internet:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armionline.net\/en\/annunci\/canne-per-modello-radom-vis-35\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canne per modello radom vis 35 | armionline.net\" \/>\n<meta property=\"og:description\" content=\"Canne per modello radom vis 35, calibro 7,65 Para e 9x21 9x21 180\u20ac 7,65 para 150\u20ac Seguici anche sul nostro sito internet:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armionline.net\/en\/annunci\/canne-per-modello-radom-vis-35\/\" \/>\n<meta property=\"og:site_name\" content=\"armionline.net\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T15:03:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1046\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/canne-per-modello-radom-vis-35\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/canne-per-modello-radom-vis-35\\\/\",\"name\":\"Canne per modello radom vis 35 | armionline.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\"},\"datePublished\":\"2026-04-15T15:03:11+00:00\",\"dateModified\":\"2026-04-15T15:03:26+00:00\",\"description\":\"Canne per modello radom vis 35, calibro 7,65 Para e 9x21 9x21 180\u20ac 7,65 para 150\u20ac Seguici anche sul nostro sito internet:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/canne-per-modello-radom-vis-35\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armionline.net\\\/annunci\\\/canne-per-modello-radom-vis-35\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/canne-per-modello-radom-vis-35\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/armionline.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classified Listings\",\"item\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Canne per modello radom vis 35\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"name\":\"armionline.net\",\"description\":\"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.\",\"publisher\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armionline.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\",\"name\":\"armionline.net\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"contentUrl\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"width\":180,\"height\":71,\"caption\":\"armionline.net\"},\"image\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canne per modello radom vis 35 | armionline.net","description":"Canne per modello radom vis 35, calibro 7,65 Para e 9x21 9x21 180\u20ac 7,65 para 150\u20ac Seguici anche sul nostro sito internet:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armionline.net\/en\/annunci\/canne-per-modello-radom-vis-35\/","og_locale":"en_US","og_type":"article","og_title":"Canne per modello radom vis 35 | armionline.net","og_description":"Canne per modello radom vis 35, calibro 7,65 Para e 9x21 9x21 180\u20ac 7,65 para 150\u20ac Seguici anche sul nostro sito internet:","og_url":"https:\/\/armionline.net\/en\/annunci\/canne-per-modello-radom-vis-35\/","og_site_name":"armionline.net","article_modified_time":"2026-04-15T15:03:26+00:00","og_image":[{"width":1046,"height":164,"url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/armionline.net\/annunci\/canne-per-modello-radom-vis-35\/","url":"https:\/\/armionline.net\/annunci\/canne-per-modello-radom-vis-35\/","name":"Canne per modello radom vis 35 | armionline.net","isPartOf":{"@id":"https:\/\/armionline.net\/#website"},"datePublished":"2026-04-15T15:03:11+00:00","dateModified":"2026-04-15T15:03:26+00:00","description":"Canne per modello radom vis 35, calibro 7,65 Para e 9x21 9x21 180\u20ac 7,65 para 150\u20ac Seguici anche sul nostro sito internet:","breadcrumb":{"@id":"https:\/\/armionline.net\/annunci\/canne-per-modello-radom-vis-35\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armionline.net\/annunci\/canne-per-modello-radom-vis-35\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/armionline.net\/annunci\/canne-per-modello-radom-vis-35\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/armionline.net\/"},{"@type":"ListItem","position":2,"name":"Classified Listings","item":"https:\/\/armionline.net\/annunci\/"},{"@type":"ListItem","position":3,"name":"Canne per modello radom vis 35"}]},{"@type":"WebSite","@id":"https:\/\/armionline.net\/#website","url":"https:\/\/armionline.net\/","name":"armionline.net","description":"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.","publisher":{"@id":"https:\/\/armionline.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armionline.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/armionline.net\/#organization","name":"armionline.net","url":"https:\/\/armionline.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/","url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","contentUrl":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","width":180,"height":71,"caption":"armionline.net"},"image":{"@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing\/18279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing"}],"about":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/types\/rtcl_listing"}],"author":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/comments?post=18279"}],"wp:attachment":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/media?parent=18279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}