{"id":18250,"date":"2026-04-10T18:12:29","date_gmt":"2026-04-10T16:12:29","guid":{"rendered":"https:\/\/armionline.net\/annunci\/sovrapposto-beretta-da-tiro\/"},"modified":"2026-04-10T18:14:02","modified_gmt":"2026-04-10T16:14:02","slug":"sovrapposto-beretta-da-tiro","status":"publish","type":"rtcl_listing","link":"https:\/\/armionline.net\/en\/annunci\/sovrapposto-beretta-da-tiro\/","title":{"rendered":"Sovrapposto Beretta da tiro"},"content":{"rendered":"<p>Fucile sovrapposto da tiro, modello speciale, calcio in radica (incisore G. Poli), custodia nuova originale. lunghezza cm. 70 (sup. \u263c inf. \u263c\u263c\u263c), peso kg. 3,520.<\/p>","protected":false},"author":4238,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-18250","rtcl_listing","type-rtcl_listing","status-publish","hentry","rtcl_category-armi-lunghe-canna-liscia","rtcl_location-alessandria","rtcl_location-piemonte","listing-item","rtcl-listing-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sovrapposto Beretta da tiro | armionline.net<\/title>\n<meta name=\"description\" content=\"Fucile sovrapposto da tiro, modello speciale, calcio in radica (incisore G. Poli), custodia nuova originale. lunghezza cm. 70 (sup. \u263c inf. \u263c\u263c\u263c), peso kg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armionline.net\/en\/annunci\/sovrapposto-beretta-da-tiro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sovrapposto Beretta da tiro | armionline.net\" \/>\n<meta property=\"og:description\" content=\"Fucile sovrapposto da tiro, modello speciale, calcio in radica (incisore G. Poli), custodia nuova originale. lunghezza cm. 70 (sup. \u263c inf. \u263c\u263c\u263c), peso kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armionline.net\/en\/annunci\/sovrapposto-beretta-da-tiro\/\" \/>\n<meta property=\"og:site_name\" content=\"armionline.net\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T16:14:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1046\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/sovrapposto-beretta-da-tiro\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/sovrapposto-beretta-da-tiro\\\/\",\"name\":\"Sovrapposto Beretta da tiro | armionline.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\"},\"datePublished\":\"2026-04-10T16:12:29+00:00\",\"dateModified\":\"2026-04-10T16:14:02+00:00\",\"description\":\"Fucile sovrapposto da tiro, modello speciale, calcio in radica (incisore G. Poli), custodia nuova originale. lunghezza cm. 70 (sup. \u263c inf. \u263c\u263c\u263c), peso kg.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/sovrapposto-beretta-da-tiro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armionline.net\\\/annunci\\\/sovrapposto-beretta-da-tiro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/sovrapposto-beretta-da-tiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/armionline.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classified Listings\",\"item\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sovrapposto Beretta da tiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"name\":\"armionline.net\",\"description\":\"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.\",\"publisher\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armionline.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\",\"name\":\"armionline.net\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"contentUrl\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"width\":180,\"height\":71,\"caption\":\"armionline.net\"},\"image\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sovrapposto Beretta da tiro | armionline.net","description":"Fucile sovrapposto da tiro, modello speciale, calcio in radica (incisore G. Poli), custodia nuova originale. lunghezza cm. 70 (sup. \u263c inf. \u263c\u263c\u263c), peso kg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armionline.net\/en\/annunci\/sovrapposto-beretta-da-tiro\/","og_locale":"en_US","og_type":"article","og_title":"Sovrapposto Beretta da tiro | armionline.net","og_description":"Fucile sovrapposto da tiro, modello speciale, calcio in radica (incisore G. Poli), custodia nuova originale. lunghezza cm. 70 (sup. \u263c inf. \u263c\u263c\u263c), peso kg.","og_url":"https:\/\/armionline.net\/en\/annunci\/sovrapposto-beretta-da-tiro\/","og_site_name":"armionline.net","article_modified_time":"2026-04-10T16:14:02+00:00","og_image":[{"width":1046,"height":164,"url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/armionline.net\/annunci\/sovrapposto-beretta-da-tiro\/","url":"https:\/\/armionline.net\/annunci\/sovrapposto-beretta-da-tiro\/","name":"Sovrapposto Beretta da tiro | armionline.net","isPartOf":{"@id":"https:\/\/armionline.net\/#website"},"datePublished":"2026-04-10T16:12:29+00:00","dateModified":"2026-04-10T16:14:02+00:00","description":"Fucile sovrapposto da tiro, modello speciale, calcio in radica (incisore G. Poli), custodia nuova originale. lunghezza cm. 70 (sup. \u263c inf. \u263c\u263c\u263c), peso kg.","breadcrumb":{"@id":"https:\/\/armionline.net\/annunci\/sovrapposto-beretta-da-tiro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armionline.net\/annunci\/sovrapposto-beretta-da-tiro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/armionline.net\/annunci\/sovrapposto-beretta-da-tiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/armionline.net\/"},{"@type":"ListItem","position":2,"name":"Classified Listings","item":"https:\/\/armionline.net\/annunci\/"},{"@type":"ListItem","position":3,"name":"Sovrapposto Beretta da tiro"}]},{"@type":"WebSite","@id":"https:\/\/armionline.net\/#website","url":"https:\/\/armionline.net\/","name":"armionline.net","description":"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.","publisher":{"@id":"https:\/\/armionline.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armionline.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/armionline.net\/#organization","name":"armionline.net","url":"https:\/\/armionline.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/","url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","contentUrl":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","width":180,"height":71,"caption":"armionline.net"},"image":{"@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing\/18250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing"}],"about":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/types\/rtcl_listing"}],"author":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/users\/4238"}],"replies":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/comments?post=18250"}],"wp:attachment":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/media?parent=18250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}