{"id":15027,"date":"2024-12-19T10:21:47","date_gmt":"2024-12-19T08:21:47","guid":{"rendered":"https:\/\/armionline.net\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/"},"modified":"2024-12-19T10:23:30","modified_gmt":"2024-12-19T08:23:30","slug":"pedersoli-trjon-target-cal-45-nuova-rif-lv1974","status":"publish","type":"rtcl_listing","link":"https:\/\/armionline.net\/en\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/","title":{"rendered":"Pedersoli Trjon &#8211; Target Cal. 45 NUOVA (Rif. LV1974)"},"content":{"rendered":"<p>Fucile Avancarica di Libera Vendita<\/p>\n<p>Marca: Pedersoli<\/p>\n<p>Modello: Trojon &#8211; Target<\/p>\n<p>Calibro: 45<\/p>\n<p>Anno riproduzione: 1845<\/p>\n<p>Lunghezza canna: 32&#8243; 5\/16<\/p>\n<p>Lunghezza totale: 1230 mm<\/p>\n<p>Canna: ottagonale<\/p>\n<p>Calcio: noce<\/p>\n<p>Scatto: steker<\/p>\n<p>Mire: regolabili in verticale<\/p>\n<p>Cartella: percussione<\/p>\n<p>Brunitura: nera<\/p>\n<p>Righe: 6<\/p>\n<p>Passo rigatura: 1:48<\/p>\n<p>Misura palla: .445 Round<\/p>\n<p>&#8211; Tabacchiera sul calcio<\/p>\n<p>(c.a. 5219)<\/p>\n<p><a href=\"https:\/\/armeriaregina.it\/it\/avancarica\/4226-pedersoli-trjon-target-cal-45.html\" target=\"_blank\" rel=\"noopener\">Scopri di pi\u00f9 su Armeria Regina<\/a><\/p>","protected":false},"author":35,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-15027","rtcl_listing","type-rtcl_listing","status-publish","hentry","rtcl_category-armi-polvere-nera","rtcl_location-treviso","rtcl_location-veneto","listing-item","rtcl-listing-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pedersoli Trjon - Target Cal. 45 NUOVA (Rif. LV1974) | armionline.net<\/title>\n<meta name=\"description\" content=\"Fucile Avancarica di Libera Vendita Marca: Pedersoli Modello: Trojon - Target Calibro: 45 Anno riproduzione: 1845 Lunghezza canna: 32&quot; 5\/16 Lunghezza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armionline.net\/en\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedersoli Trjon - Target Cal. 45 NUOVA (Rif. LV1974) | armionline.net\" \/>\n<meta property=\"og:description\" content=\"Fucile Avancarica di Libera Vendita Marca: Pedersoli Modello: Trojon - Target Calibro: 45 Anno riproduzione: 1845 Lunghezza canna: 32&quot; 5\/16 Lunghezza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armionline.net\/en\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/\" \/>\n<meta property=\"og:site_name\" content=\"armionline.net\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-19T08:23:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1046\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\\\/\",\"name\":\"Pedersoli Trjon - Target Cal. 45 NUOVA (Rif. LV1974) | armionline.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\"},\"datePublished\":\"2024-12-19T08:21:47+00:00\",\"dateModified\":\"2024-12-19T08:23:30+00:00\",\"description\":\"Fucile Avancarica di Libera Vendita Marca: Pedersoli Modello: Trojon - Target Calibro: 45 Anno riproduzione: 1845 Lunghezza canna: 32\\\" 5\\\/16 Lunghezza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armionline.net\\\/annunci\\\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/armionline.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classified Listings\",\"item\":\"https:\\\/\\\/armionline.net\\\/annunci\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pedersoli Trjon &#8211; Target Cal. 45 NUOVA (Rif. LV1974)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#website\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"name\":\"armionline.net\",\"description\":\"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.\",\"publisher\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armionline.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#organization\",\"name\":\"armionline.net\",\"url\":\"https:\\\/\\\/armionline.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"contentUrl\":\"https:\\\/\\\/armionline.net\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-AOL-ridotto.png\",\"width\":180,\"height\":71,\"caption\":\"armionline.net\"},\"image\":{\"@id\":\"https:\\\/\\\/armionline.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pedersoli Trjon - Target Cal. 45 NUOVA (Rif. LV1974) | armionline.net","description":"Fucile Avancarica di Libera Vendita Marca: Pedersoli Modello: Trojon - Target Calibro: 45 Anno riproduzione: 1845 Lunghezza canna: 32\" 5\/16 Lunghezza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armionline.net\/en\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/","og_locale":"en_US","og_type":"article","og_title":"Pedersoli Trjon - Target Cal. 45 NUOVA (Rif. LV1974) | armionline.net","og_description":"Fucile Avancarica di Libera Vendita Marca: Pedersoli Modello: Trojon - Target Calibro: 45 Anno riproduzione: 1845 Lunghezza canna: 32\" 5\/16 Lunghezza","og_url":"https:\/\/armionline.net\/en\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/","og_site_name":"armionline.net","article_modified_time":"2024-12-19T08:23:30+00:00","og_image":[{"width":1046,"height":164,"url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-Esteso.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/armionline.net\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/","url":"https:\/\/armionline.net\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/","name":"Pedersoli Trjon - Target Cal. 45 NUOVA (Rif. LV1974) | armionline.net","isPartOf":{"@id":"https:\/\/armionline.net\/#website"},"datePublished":"2024-12-19T08:21:47+00:00","dateModified":"2024-12-19T08:23:30+00:00","description":"Fucile Avancarica di Libera Vendita Marca: Pedersoli Modello: Trojon - Target Calibro: 45 Anno riproduzione: 1845 Lunghezza canna: 32\" 5\/16 Lunghezza","breadcrumb":{"@id":"https:\/\/armionline.net\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armionline.net\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/armionline.net\/annunci\/pedersoli-trjon-target-cal-45-nuova-rif-lv1974\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/armionline.net\/"},{"@type":"ListItem","position":2,"name":"Classified Listings","item":"https:\/\/armionline.net\/annunci\/"},{"@type":"ListItem","position":3,"name":"Pedersoli Trjon &#8211; Target Cal. 45 NUOVA (Rif. LV1974)"}]},{"@type":"WebSite","@id":"https:\/\/armionline.net\/#website","url":"https:\/\/armionline.net\/","name":"armionline.net","description":"Il sito di annunci di vendita di armi per privati e armerie. Pubblica o trova annunci di armi usate, armi nuove, ottiche, accessori, ricarica e altro.","publisher":{"@id":"https:\/\/armionline.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armionline.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/armionline.net\/#organization","name":"armionline.net","url":"https:\/\/armionline.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/","url":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","contentUrl":"https:\/\/armionline.net\/wp-content\/uploads\/2024\/09\/logo-AOL-ridotto.png","width":180,"height":71,"caption":"armionline.net"},"image":{"@id":"https:\/\/armionline.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing\/15027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/rtcl_listing"}],"about":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/types\/rtcl_listing"}],"author":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/comments?post=15027"}],"wp:attachment":[{"href":"https:\/\/armionline.net\/en\/wp-json\/wp\/v2\/media?parent=15027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}